{"id":35,"count":1,"description":"","link":"https:\/\/expeditoursbolivia.com\/en\/tag\/selva-virgen-bolivia\/","name":"Selva virgen Bolivia","slug":"selva-virgen-bolivia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/expeditoursbolivia.com\/en\/wp-json\/wp\/v2\/tags\/35"}],"collection":[{"href":"https:\/\/expeditoursbolivia.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/expeditoursbolivia.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/expeditoursbolivia.com\/en\/wp-json\/wp\/v2\/posts?tags=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}